{"id":1481,"date":"2016-09-21T10:05:56","date_gmt":"2016-09-21T17:05:56","guid":{"rendered":"https:\/\/www.website-122f066c.bangweb.site\/website\/?p=1481"},"modified":"2016-09-21T10:05:56","modified_gmt":"2016-09-21T17:05:56","slug":"la-experiencia-ha-traspasado-fronteras","status":"publish","type":"post","link":"https:\/\/grupobasica.com\/en\/la-experiencia-ha-traspasado-fronteras\/","title":{"rendered":"La experiencia que ha traspasado fronteras"},"content":{"rendered":"<p style=\"text-align: left;\"><span style=\"font-weight: 400;\">Tijuana ha sido detonador de transformaci\u00f3n en el noroeste de M\u00e9xico, sobre todo en el desarrollo inmobiliario con espacios nuevos y redise\u00f1o de espacios existentes. Hoy en d\u00eda Tijuana cuenta con arquitectos de trayectoria nacional e internacional que est\u00e1n dibujando la nueva imagen de la ciu<\/span><span style=\"font-weight: 400;\">dad<\/span><span style=\"font-weight: 400;\">; existen empresas que han colaborado en conjunto para transformar los nuevos proyectos en una realidad, tal es el caso de Grupo Basica.<\/span><\/p>\n<p style=\"text-align: left;\">Entre los que se destaca su colaboraci\u00f3n se encuentran proyectos como: Aeropuerto Internacional de Tijuana, Bit Center, Care Fusion, CEART, Centro de Convenciones de Rosarito, Museo Ambar, Museo del Vino, Plantronics, World Trade Center Tijuana, Torre Cosmopolitan, VIA Corporativo, entre otros proyectos en Latinoam\u00e9rica.<\/p>\n<p style=\"text-align: left;\">Por m\u00e1s de 16 a\u00f1os <strong>Grupo Basica<\/strong> ha llevado a la realidad proyectos de fachadas ventiladas y dobles fachadas a trav\u00e9s del dise\u00f1o de ingenier\u00eda que realiza el equipo t\u00e9cnico. Basica estudia el proyecto para proponer el sistema m\u00e1s adecuado para cada proyecto. Se enfoca en la \u00a0maximizaci\u00f3n de recursos y en las consecuencias de afectaci\u00f3n a su entorno. Entre sus habilidades mejora la habitabilidad y calidad de vida para que la obra trascienda en el tiempo.<\/p>\n<p style=\"text-align: left;\">Uno de los objetivos de Equipo Basica es brindar la mejor propuesta t\u00e9cnica para que la fachada beneficie a su proyecto aport\u00e1ndole valor.<\/p>\n<p style=\"text-align: left;\">La arquitectura sin duda ha evolucionado en estos \u00faltimos a\u00f1os y <strong>Grupo Basica<\/strong> sabe que no hay imposibles para dise\u00f1ar, planear e innovar.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Tijuana ha sido detonador de transformaci\u00f3n en el noroeste de M\u00e9xico, sobre todo en el desarrollo inmobiliario con espacios nuevos y redise\u00f1o de espacios existentes. Hoy en d\u00eda Tijuana cuenta con arquitectos de trayectoria nacional e internacional que est\u00e1n dibujando&#8230;<\/p>","protected":false},"author":2,"featured_media":1644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13,19],"tags":[36,54,55,22,15,56],"class_list":["post-1481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grupo-basica","category-proyectos-basica","tag-arquitectura","tag-care-fusion","tag-colombia","tag-fachadas","tag-via-corportativo","tag-wtc-tijuana"],"yoast_head":"\n<title>La experiencia que ha traspasado fronteras | Grupo Basica\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La experiencia que ha traspasado fronteras | Grupo Basica\u00ae\" \/>\n<meta property=\"og:description\" content=\"Tijuana ha sido detonador de transformaci\u00f3n en el noroeste de M\u00e9xico, sobre todo en el desarrollo inmobiliario con espacios nuevos y redise\u00f1o de espacios existentes. Hoy en d\u00eda Tijuana cuenta con arquitectos de trayectoria nacional e internacional que est\u00e1n dibujando...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Basica\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-21T17:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.website-122f066c.bangweb.site\/wp-content\/uploads\/2016\/09\/Basica-Hearth-Beat-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"adriana liv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adriana liv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/\"},\"author\":{\"name\":\"adriana liv\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/person\\\/afa17a59e6bb68be638d482da25979c5\"},\"headline\":\"La experiencia que ha traspasado fronteras\",\"datePublished\":\"2016-09-21T17:05:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/\"},\"wordCount\":262,\"publisher\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/Basica-Hearth-Beat-01.png\",\"keywords\":[\"arquitectura\",\"Care Fusion\",\"Colombia\",\"fachadas\",\"VIA Corportativo\",\"WTC Tijuana\"],\"articleSection\":[\"Grupo Basica\",\"Proyectos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/\",\"name\":\"La experiencia que ha traspasado fronteras | Grupo Basica\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/Basica-Hearth-Beat-01.png\",\"datePublished\":\"2016-09-21T17:05:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/Basica-Hearth-Beat-01.png\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/Basica-Hearth-Beat-01.png\",\"width\":1000,\"height\":628,\"caption\":\"Basica trayectoria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/la-experiencia-ha-traspasado-fronteras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/grupobasica.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La experiencia que ha traspasado fronteras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#website\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/\",\"name\":\"Grupo Basica\u00a9\",\"description\":\"Consultor\u00eda, Dise\u00f1o y Sistema de Fachadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\"},\"alternateName\":\"Basica\u00a9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\",\"name\":\"Grupo Basica\u00a9\",\"alternateName\":\"Basica\u00a9\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-grupobasica-696px.png\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-grupobasica-696px.png\",\"width\":696,\"height\":696,\"caption\":\"Grupo Basica\u00a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/person\\\/afa17a59e6bb68be638d482da25979c5\",\"name\":\"adriana liv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"caption\":\"adriana liv\"},\"url\":\"https:\\\/\\\/grupobasica.com\\\/en\\\/author\\\/adriana\\\/\"}]}<\/script>\n","yoast_head_json":{"title":"La experiencia que ha traspasado fronteras | Grupo Basica\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/","og_locale":"en_US","og_type":"article","og_title":"La experiencia que ha traspasado fronteras | Grupo Basica\u00ae","og_description":"Tijuana ha sido detonador de transformaci\u00f3n en el noroeste de M\u00e9xico, sobre todo en el desarrollo inmobiliario con espacios nuevos y redise\u00f1o de espacios existentes. Hoy en d\u00eda Tijuana cuenta con arquitectos de trayectoria nacional e internacional que est\u00e1n dibujando...","og_url":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/","og_site_name":"Grupo Basica\u00ae","article_published_time":"2016-09-21T17:05:56+00:00","og_image":[{"width":1000,"height":628,"url":"https:\/\/www.website-122f066c.bangweb.site\/wp-content\/uploads\/2016\/09\/Basica-Hearth-Beat-01.png","type":"image\/png"}],"author":"adriana liv","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adriana liv","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/#article","isPartOf":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/"},"author":{"name":"adriana liv","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/person\/afa17a59e6bb68be638d482da25979c5"},"headline":"La experiencia que ha traspasado fronteras","datePublished":"2016-09-21T17:05:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/"},"wordCount":262,"publisher":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/#primaryimage"},"thumbnailUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/09\/Basica-Hearth-Beat-01.png","keywords":["arquitectura","Care Fusion","Colombia","fachadas","VIA Corportativo","WTC Tijuana"],"articleSection":["Grupo Basica","Proyectos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/","url":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/","name":"La experiencia que ha traspasado fronteras | Grupo Basica\u00ae","isPartOf":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/#primaryimage"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/#primaryimage"},"thumbnailUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/09\/Basica-Hearth-Beat-01.png","datePublished":"2016-09-21T17:05:56+00:00","breadcrumb":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/#primaryimage","url":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/09\/Basica-Hearth-Beat-01.png","contentUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/09\/Basica-Hearth-Beat-01.png","width":1000,"height":628,"caption":"Basica trayectoria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.website-122f066c.bangweb.site\/la-experiencia-ha-traspasado-fronteras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/grupobasica.com\/"},{"@type":"ListItem","position":2,"name":"La experiencia que ha traspasado fronteras"}]},{"@type":"WebSite","@id":"https:\/\/www.website-122f066c.bangweb.site\/#website","url":"https:\/\/www.website-122f066c.bangweb.site\/","name":"Grupo Basica\u00a9","description":"Consultor\u00eda, Dise\u00f1o y Sistema de Fachadas","publisher":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization"},"alternateName":"Basica\u00a9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.website-122f066c.bangweb.site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization","name":"Grupo Basica\u00a9","alternateName":"Basica\u00a9","url":"https:\/\/www.website-122f066c.bangweb.site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/logo\/image\/","url":"https:\/\/grupobasica.com\/wp-content\/uploads\/2023\/03\/logo-grupobasica-696px.png","contentUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2023\/03\/logo-grupobasica-696px.png","width":696,"height":696,"caption":"Grupo Basica\u00a9"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/person\/afa17a59e6bb68be638d482da25979c5","name":"adriana liv","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","url":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","contentUrl":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","caption":"adriana liv"},"url":"https:\/\/grupobasica.com\/en\/author\/adriana\/"}]}},"_links":{"self":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts\/1481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/comments?post=1481"}],"version-history":[{"count":0,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts\/1481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/media\/1644"}],"wp:attachment":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/media?parent=1481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/categories?post=1481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/tags?post=1481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}