{"id":40771,"date":"2019-06-03T13:05:02","date_gmt":"2019-06-03T20:05:02","guid":{"rendered":"https:\/\/www.website-122f066c.bangweb.site\/website\/?p=40771"},"modified":"2019-06-03T13:05:02","modified_gmt":"2019-06-03T20:05:02","slug":"creatividad-y-diseno-con-plafones-de-madera","status":"publish","type":"post","link":"https:\/\/grupobasica.com\/en\/creatividad-y-diseno-con-plafones-de-madera\/","title":{"rendered":"Creatividad y dise\u00f1o con plafones de madera"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El plaf\u00f3n de madera hoy cobra un protagonismo de gran impacto en interiorismo, ayudando a crear espacios que inspiran. La combinaci\u00f3n con muebles y accesorios, nos dar\u00e1n un equilibrio de elementos dentro del dise\u00f1o de interiores, mejorando el confort visual. Factores como la iluminaci\u00f3n y el dise\u00f1o de plaf\u00f3n nos dar\u00e1n la pauta para generar confort al usuario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al hablar del dise\u00f1o de interiores no se puede dejar de lado la <a href=\"https:\/\/grupobasica.com\/en\/website\/materiales\/plafones-decorativos-mezcla-de-estilo-y-color\/\">creatividad<\/a>, \u00e9sta es la pieza fundamental para la creaci\u00f3n de espacios confortables. El juego de sombras, las combinaciones de color y formas existentes, nos permiten proyectar nuestras ideas y dise\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el dise\u00f1o en interiores suele centrarse en las paredes y pisos, ya que son los que llevan una gran carga est\u00e9tica, por lo que se desaprovecha toda la potencia que puede generar un sistema de plaf\u00f3n capaz de lograr un ambiente m\u00e1s atractivo y moderno.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/creatividad-y-diseno-con-plafones-de-madera-0002-basica-723x1100.jpg\" alt=\"Demostraci\u00f3n de plaf\u00f3n de madera en interiores\" class=\"wp-image-40772\"\/><figcaption>Demostraci\u00f3n de plaf\u00f3n de madera en interiores<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La calidez de la madera<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La madera es un material reconocido por sus propiedades extraordinarias que le permiten adaptarse a muchos usos. Este elemento de la naturaleza potencia la sensaci\u00f3n de tranquilidad y relajaci\u00f3n en los ambientes en los que se integra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las nuevas tendencias colocan a los plafones de madera como una propuesta inspiradora para el arquitecto, personalizando espacios que nos invitan a contemplar y admirar sus dise\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, para preservar la imagen natural de los plafones de madera, necesitaremos de un mantenimiento constante. No obstante, en la actualidad existen nuevas soluciones que permiten imitar la apariencia natural de la madera.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"609\" height=\"332\" src=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/creatividad-y-diseno-con-plafones-de-madera-0004-basica-e1559604117269.jpg\" alt=\"Demostraci\u00f3n de plaf\u00f3n de madera en exteriores\" class=\"wp-image-40773\" srcset=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/creatividad-y-diseno-con-plafones-de-madera-0004-basica-e1559604117269.jpg 609w, https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/creatividad-y-diseno-con-plafones-de-madera-0004-basica-e1559604117269-300x164.jpg 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/><figcaption>Demostraci\u00f3n de plaf\u00f3n de madera en exteriores<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro de las soluciones existentes, se encuentran los plafones de madera Aluskin\u00ae, con su gama de acabados naturales. La t\u00e9cnica de sublimaci\u00f3n aplicada permite tener la apariencia de la madera por mucho m\u00e1s tiempo y con un m\u00ednimo mantenimiento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Plafones de madera Aluskin\u00ae<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La l\u00ednea de <a href=\"https:\/\/grupobasica.com\/en\/website\/productos\/paneles-metalicos\/#plafon\">plafones Aluskin\u00ae<\/a>, cuenta con dise\u00f1os atractivos fabricados en aluminio y aluminio extruido que asemejan la forma de un plaf\u00f3n de madera natural. De acuerdo a los requerimientos del proyecto, se logran crear dise\u00f1os continuos proporcionando una est\u00e9tica limpia y moderna. Los plafones se sujetan mediante cargadores y canaletas de carga, siguiendo el sistema tradicional. Algunos modelos pueden ser montados \u00fanicamente a presi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/plafones-aluskin-creatividad-y-diseno-con-plafones-de-madera-0001-basica.jpg\" alt=\"Plafa\u00f3n de madera marca Aluskin\u00ae\" class=\"wp-image-40774\" srcset=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/plafones-aluskin-creatividad-y-diseno-con-plafones-de-madera-0001-basica.jpg 1000w, https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/plafones-aluskin-creatividad-y-diseno-con-plafones-de-madera-0001-basica-300x200.jpg 300w, https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/plafones-aluskin-creatividad-y-diseno-con-plafones-de-madera-0001-basica-768x512.jpg 768w, https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/plafones-aluskin-creatividad-y-diseno-con-plafones-de-madera-0001-basica-700x467.jpg 700w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption>Plaf\u00f3n de madera marca Aluskin\u00ae<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Crea espacios que inspiran. Te invitamos a conocer la l\u00ednea de plafones sublimados de madera de <a href=\"https:\/\/grupobasica.com\/en\/website\/productos\/paneles-metalicos\/\">Aluskin\u00ae<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los plafones de madera son hoy protagonistas en dise\u00f1o de interiores, las nuevas tendencias los colocan como una propuesta inspiradora para el arquitecto.<\/p>","protected":false},"author":2,"featured_media":40775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-40771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"\n<title>Creatividad y dise\u00f1o con plafones de madera | Grupo Basica\u00ae<\/title>\n<meta name=\"description\" content=\"Los plafones de madera son hoy protagonistas en dise\u00f1o de interiores, las nuevas tendencias los colocan como una propuesta inspiradora para el arquitecto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creatividad y dise\u00f1o con plafones de madera | Grupo Basica\u00ae\" \/>\n<meta property=\"og:description\" content=\"Los plafones de madera son hoy protagonistas en dise\u00f1o de interiores, las nuevas tendencias los colocan como una propuesta inspiradora para el arquitecto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Basica\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-03T20:05:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.website-122f066c.bangweb.site\/wp-content\/uploads\/2019\/06\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adriana liv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adriana liv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/\"},\"author\":{\"name\":\"adriana liv\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/person\\\/afa17a59e6bb68be638d482da25979c5\"},\"headline\":\"Creatividad y dise\u00f1o con plafones de madera\",\"datePublished\":\"2019-06-03T20:05:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/\"},\"wordCount\":437,\"publisher\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/\",\"name\":\"Creatividad y dise\u00f1o con plafones de madera | Grupo Basica\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg\",\"datePublished\":\"2019-06-03T20:05:02+00:00\",\"description\":\"Los plafones de madera son hoy protagonistas en dise\u00f1o de interiores, las nuevas tendencias los colocan como una propuesta inspiradora para el arquitecto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg\",\"width\":1100,\"height\":687,\"caption\":\"Creatividad y dise\u00f1o con plafones | Grupo Basica\u00ae\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/creatividad-y-diseno-con-plafones-de-madera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/grupobasica.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Creatividad y dise\u00f1o con plafones de madera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#website\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/\",\"name\":\"Grupo Basica\u00a9\",\"description\":\"Consultor\u00eda, Dise\u00f1o y Sistema de Fachadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\"},\"alternateName\":\"Basica\u00a9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\",\"name\":\"Grupo Basica\u00a9\",\"alternateName\":\"Basica\u00a9\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-grupobasica-696px.png\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-grupobasica-696px.png\",\"width\":696,\"height\":696,\"caption\":\"Grupo Basica\u00a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/person\\\/afa17a59e6bb68be638d482da25979c5\",\"name\":\"adriana liv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"caption\":\"adriana liv\"},\"url\":\"https:\\\/\\\/grupobasica.com\\\/en\\\/author\\\/adriana\\\/\"}]}<\/script>\n","yoast_head_json":{"title":"Creatividad y dise\u00f1o con plafones de madera | Grupo Basica\u00ae","description":"Los plafones de madera son hoy protagonistas en dise\u00f1o de interiores, las nuevas tendencias los colocan como una propuesta inspiradora para el arquitecto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/","og_locale":"en_US","og_type":"article","og_title":"Creatividad y dise\u00f1o con plafones de madera | Grupo Basica\u00ae","og_description":"Los plafones de madera son hoy protagonistas en dise\u00f1o de interiores, las nuevas tendencias los colocan como una propuesta inspiradora para el arquitecto.","og_url":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/","og_site_name":"Grupo Basica\u00ae","article_published_time":"2019-06-03T20:05:02+00:00","og_image":[{"width":1100,"height":687,"url":"https:\/\/www.website-122f066c.bangweb.site\/wp-content\/uploads\/2019\/06\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg","type":"image\/jpeg"}],"author":"adriana liv","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adriana liv","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/#article","isPartOf":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/"},"author":{"name":"adriana liv","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/person\/afa17a59e6bb68be638d482da25979c5"},"headline":"Creatividad y dise\u00f1o con plafones de madera","datePublished":"2019-06-03T20:05:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/"},"wordCount":437,"publisher":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/#primaryimage"},"thumbnailUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg","articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/","url":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/","name":"Creatividad y dise\u00f1o con plafones de madera | Grupo Basica\u00ae","isPartOf":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/#primaryimage"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/#primaryimage"},"thumbnailUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg","datePublished":"2019-06-03T20:05:02+00:00","description":"Los plafones de madera son hoy protagonistas en dise\u00f1o de interiores, las nuevas tendencias los colocan como una propuesta inspiradora para el arquitecto.","breadcrumb":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/#primaryimage","url":"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg","contentUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2019\/06\/portada-creatividad-y-diseno-con-plafones-de-madera-0003-basica.jpg","width":1100,"height":687,"caption":"Creatividad y dise\u00f1o con plafones | Grupo Basica\u00ae"},{"@type":"BreadcrumbList","@id":"https:\/\/www.website-122f066c.bangweb.site\/creatividad-y-diseno-con-plafones-de-madera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/grupobasica.com\/"},{"@type":"ListItem","position":2,"name":"Creatividad y dise\u00f1o con plafones de madera"}]},{"@type":"WebSite","@id":"https:\/\/www.website-122f066c.bangweb.site\/#website","url":"https:\/\/www.website-122f066c.bangweb.site\/","name":"Grupo Basica\u00a9","description":"Consultor\u00eda, Dise\u00f1o y Sistema de Fachadas","publisher":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization"},"alternateName":"Basica\u00a9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.website-122f066c.bangweb.site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization","name":"Grupo Basica\u00a9","alternateName":"Basica\u00a9","url":"https:\/\/www.website-122f066c.bangweb.site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/logo\/image\/","url":"https:\/\/grupobasica.com\/wp-content\/uploads\/2023\/03\/logo-grupobasica-696px.png","contentUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2023\/03\/logo-grupobasica-696px.png","width":696,"height":696,"caption":"Grupo Basica\u00a9"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/person\/afa17a59e6bb68be638d482da25979c5","name":"adriana liv","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","url":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","contentUrl":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","caption":"adriana liv"},"url":"https:\/\/grupobasica.com\/en\/author\/adriana\/"}]}},"_links":{"self":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts\/40771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/comments?post=40771"}],"version-history":[{"count":0,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts\/40771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/media\/40775"}],"wp:attachment":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/media?parent=40771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/categories?post=40771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/tags?post=40771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}