{"id":953,"date":"2016-07-07T22:28:46","date_gmt":"2016-07-08T05:28:46","guid":{"rendered":"https:\/\/www.website-122f066c.bangweb.site\/website\/?p=953"},"modified":"2016-07-07T22:28:46","modified_gmt":"2016-07-08T05:28:46","slug":"fachada-eficiente-segun-el-entorno","status":"publish","type":"post","link":"https:\/\/grupobasica.com\/en\/fachada-eficiente-segun-el-entorno\/","title":{"rendered":"Fachada Eficiente: Dise\u00f1o de fachada seg\u00fan el entorno"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Una fachada eficiente toma en cuenta ciertos factores para un mejor provecho de la instalaci\u00f3n. El dise\u00f1o, colocaci\u00f3n y material de la&nbsp;fachada&nbsp;bio-clim\u00e1tica debe centrarse en la eficiencia energ\u00e9tica. As\u00ed como los beneficios que se pueden obtener para la edificaci\u00f3n y sus habitantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-orientaci-n-solar-elemento-clave-para-la-fachada-eficiente\">Orientaci\u00f3n solar, elemento clave para la fachada eficiente<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es de suma importancia conocer la direcci\u00f3n predominante en que se dirige el viento de la zona donde se ubicar\u00e1 la fachada. Para que conforme a ello se ubique y dise\u00f1e la misma. Este punto contribuir\u00e1 a mayores p\u00e9rdidas o una eficiencia energ\u00e9tica, seg\u00fan sea el caso de cada edificaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone wp-image-40355 size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"748\" height=\"422\" src=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-01-diagrama-de-orientacion-solar-grupobasica.jpg\" alt=\"Diagrama sobre la orientaci\u00f3n correcta para una fachada eficiente - Fachada Eficiente: Dise\u00f1o de fachada seg\u00fan el entorno - Grupo Basica\u00ae\" class=\"wp-image-40355\" srcset=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-01-diagrama-de-orientacion-solar-grupobasica.jpg 748w, https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-01-diagrama-de-orientacion-solar-grupobasica-300x169.jpg 300w, https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-01-diagrama-de-orientacion-solar-grupobasica-700x395.jpg 700w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><figcaption>Diagrama sobre la orientaci\u00f3n correcta para una fachada eficiente<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ptima-cantidad-de-ventanas-para-una-mejor-eficiencia\">\u00d3ptima cantidad de ventanas para una mejor eficiencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Contar con una cantidad \u00f3ptima de ventanas en relaci\u00f3n a la orientaci\u00f3n solar mejora la funcionalidad de tu fachada eficiente. Seg\u00fan la orientaci\u00f3n del sol la fachada&nbsp;al sur debe contar con un mayor porcentaje de ventanas; mientras que la fachada norte cuenta con un porcentaje menor. Esto ayudar\u00e1 de manera muy favorable a reducir las demandas energ\u00e9ticas.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone size-full wp-image-40356\"><img decoding=\"async\" width=\"749\" height=\"413\" src=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-02-porcentaje-de-ventanas-segun-orientacion-solar-grupobasica.jpg\" alt=\"Tabla sobre el porcentaje \u00f3ptimo de ventanas seg\u00fan la orientaci\u00f3n solar para una fachada eficiente - Fachada Eficiente: Dise\u00f1o de fachada seg\u00fan el entorno - Grupo Basica\u00ae\" class=\"wp-image-40356\" srcset=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-02-porcentaje-de-ventanas-segun-orientacion-solar-grupobasica.jpg 749w, https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-02-porcentaje-de-ventanas-segun-orientacion-solar-grupobasica-300x165.jpg 300w, https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-02-porcentaje-de-ventanas-segun-orientacion-solar-grupobasica-700x386.jpg 700w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><figcaption>Porcentaje \u00f3ptimo de ventanas seg\u00fan la orientaci\u00f3n solar para una fachada eficiente<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Del mismo modo se puede integrar al dise\u00f1o alguna ventana o apertura en la zona superior o zonas de paso. Esto favorece la ventilaci\u00f3n y refrigeraci\u00f3n natural pasiva. Sobre todo en zonas donde los veranos son m\u00e1s calurosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante tener en cuenta la orientaci\u00f3n del proyecto arquitect\u00f3nico. Ya que seg\u00fan la zona clim\u00e1tica, caracter\u00edsticas del clima local y la presencia de obst\u00e1culos \u2014naturales u otras edificaciones\u2014 la aportaci\u00f3n solar natural, circulaci\u00f3n y direcci\u00f3n de los vientos predominantes pueden variar. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Basica\u00ae estamos listos para brindar la soluci\u00f3n requerida para tu fachada eficiente.\u00a0Te invitamos a conocer nuestros proyectos realizados y servicios visitando <a href=\"https:\/\/grupobasica.com\/en\/\">www.grupobasica.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Una fachada eficiente toma cuenta factores como dise\u00f1o, colocaci\u00f3n y material de la\u00a0fachada\u00a0bioclim\u00e1tica para una mejor eficiencia energ\u00e9tica.<\/p>","protected":false},"author":2,"featured_media":40357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28,50],"tags":[48,39,49,14],"class_list":["post-953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diseno","category-sustentabilidad","tag-diseno-de-fachadas","tag-eficiencia-energetica","tag-fachada-eficiente","tag-sustentabilidad"],"yoast_head":"\n<title>Fachada Eficiente: Dise\u00f1o de fachadas seg\u00fan el entorno - Grupo Basica\u00ae<\/title>\n<meta name=\"description\" content=\"Una fachada eficiente toma cuenta factores como dise\u00f1o, colocaci\u00f3n y material de la\u00a0fachada\u00a0bioclim\u00e1tica para una mejor eficiencia energ\u00e9tica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fachada Eficiente: Dise\u00f1o de fachadas seg\u00fan el entorno - Grupo Basica\u00ae\" \/>\n<meta property=\"og:description\" content=\"Una fachada eficiente toma cuenta factores como dise\u00f1o, colocaci\u00f3n y material de la\u00a0fachada\u00a0bioclim\u00e1tica para una mejor eficiencia energ\u00e9tica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Basica\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-08T05:28:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.website-122f066c.bangweb.site\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adriana liv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adriana liv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/\"},\"author\":{\"name\":\"adriana liv\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/person\\\/afa17a59e6bb68be638d482da25979c5\"},\"headline\":\"Fachada Eficiente: Dise\u00f1o de fachada seg\u00fan el entorno\",\"datePublished\":\"2016-07-08T05:28:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/\"},\"wordCount\":343,\"publisher\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg\",\"keywords\":[\"dise\u00f1o de fachada\",\"eficiencia energ\u00e9tica\",\"fachada eficiente\",\"sustentabilidad\"],\"articleSection\":[\"Dise\u00f1o\",\"Sustentabilidad\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/\",\"name\":\"Fachada Eficiente: Dise\u00f1o de fachadas seg\u00fan el entorno - Grupo Basica\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg\",\"datePublished\":\"2016-07-08T05:28:46+00:00\",\"description\":\"Una fachada eficiente toma cuenta factores como dise\u00f1o, colocaci\u00f3n y material de la\u00a0fachada\u00a0bioclim\u00e1tica para una mejor eficiencia energ\u00e9tica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg\",\"width\":1100,\"height\":687},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/fachada-eficiente-segun-el-entorno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/grupobasica.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fachada Eficiente: Dise\u00f1o de fachada seg\u00fan el entorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#website\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/\",\"name\":\"Grupo Basica\u00a9\",\"description\":\"Consultor\u00eda, Dise\u00f1o y Sistema de Fachadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\"},\"alternateName\":\"Basica\u00a9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\",\"name\":\"Grupo Basica\u00a9\",\"alternateName\":\"Basica\u00a9\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-grupobasica-696px.png\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-grupobasica-696px.png\",\"width\":696,\"height\":696,\"caption\":\"Grupo Basica\u00a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/person\\\/afa17a59e6bb68be638d482da25979c5\",\"name\":\"adriana liv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"caption\":\"adriana liv\"},\"url\":\"https:\\\/\\\/grupobasica.com\\\/en\\\/author\\\/adriana\\\/\"}]}<\/script>\n","yoast_head_json":{"title":"Fachada Eficiente: Dise\u00f1o de fachadas seg\u00fan el entorno - Grupo Basica\u00ae","description":"Una fachada eficiente toma cuenta factores como dise\u00f1o, colocaci\u00f3n y material de la\u00a0fachada\u00a0bioclim\u00e1tica para una mejor eficiencia energ\u00e9tica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/","og_locale":"en_US","og_type":"article","og_title":"Fachada Eficiente: Dise\u00f1o de fachadas seg\u00fan el entorno - Grupo Basica\u00ae","og_description":"Una fachada eficiente toma cuenta factores como dise\u00f1o, colocaci\u00f3n y material de la\u00a0fachada\u00a0bioclim\u00e1tica para una mejor eficiencia energ\u00e9tica.","og_url":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/","og_site_name":"Grupo Basica\u00ae","article_published_time":"2016-07-08T05:28:46+00:00","og_image":[{"width":1100,"height":687,"url":"https:\/\/www.website-122f066c.bangweb.site\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg","type":"image\/jpeg"}],"author":"adriana liv","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adriana liv","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/#article","isPartOf":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/"},"author":{"name":"adriana liv","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/person\/afa17a59e6bb68be638d482da25979c5"},"headline":"Fachada Eficiente: Dise\u00f1o de fachada seg\u00fan el entorno","datePublished":"2016-07-08T05:28:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/"},"wordCount":343,"publisher":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/#primaryimage"},"thumbnailUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg","keywords":["dise\u00f1o de fachada","eficiencia energ\u00e9tica","fachada eficiente","sustentabilidad"],"articleSection":["Dise\u00f1o","Sustentabilidad"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/","url":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/","name":"Fachada Eficiente: Dise\u00f1o de fachadas seg\u00fan el entorno - Grupo Basica\u00ae","isPartOf":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/#primaryimage"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/#primaryimage"},"thumbnailUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg","datePublished":"2016-07-08T05:28:46+00:00","description":"Una fachada eficiente toma cuenta factores como dise\u00f1o, colocaci\u00f3n y material de la\u00a0fachada\u00a0bioclim\u00e1tica para una mejor eficiencia energ\u00e9tica.","breadcrumb":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/#primaryimage","url":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg","contentUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/07\/fachada-eficiente-segun-el-entorno-portada-grupobasica.jpg","width":1100,"height":687},{"@type":"BreadcrumbList","@id":"https:\/\/www.website-122f066c.bangweb.site\/fachada-eficiente-segun-el-entorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/grupobasica.com\/"},{"@type":"ListItem","position":2,"name":"Fachada Eficiente: Dise\u00f1o de fachada seg\u00fan el entorno"}]},{"@type":"WebSite","@id":"https:\/\/www.website-122f066c.bangweb.site\/#website","url":"https:\/\/www.website-122f066c.bangweb.site\/","name":"Grupo Basica\u00a9","description":"Consultor\u00eda, Dise\u00f1o y Sistema de Fachadas","publisher":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization"},"alternateName":"Basica\u00a9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.website-122f066c.bangweb.site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization","name":"Grupo Basica\u00a9","alternateName":"Basica\u00a9","url":"https:\/\/www.website-122f066c.bangweb.site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/logo\/image\/","url":"https:\/\/grupobasica.com\/wp-content\/uploads\/2023\/03\/logo-grupobasica-696px.png","contentUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2023\/03\/logo-grupobasica-696px.png","width":696,"height":696,"caption":"Grupo Basica\u00a9"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/person\/afa17a59e6bb68be638d482da25979c5","name":"adriana liv","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","url":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","contentUrl":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","caption":"adriana liv"},"url":"https:\/\/grupobasica.com\/en\/author\/adriana\/"}]}},"_links":{"self":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts\/953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/comments?post=953"}],"version-history":[{"count":0,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts\/953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/media\/40357"}],"wp:attachment":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/media?parent=953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/categories?post=953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/tags?post=953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}