{"id":962,"date":"2016-08-30T15:26:56","date_gmt":"2016-08-30T22:26:56","guid":{"rendered":"https:\/\/www.website-122f066c.bangweb.site\/website\/?p=962"},"modified":"2016-08-30T15:26:56","modified_gmt":"2016-08-30T22:26:56","slug":"nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano","status":"publish","type":"post","link":"https:\/\/grupobasica.com\/en\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/","title":{"rendered":"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano?"},"content":{"rendered":"<p style=\"text-align: left;\">Una de las mayores ventajas de una fachada ventilada es la eficiencia energ\u00e9tica que brinda a las edificaciones. Ya que su aislamiento es capaz de reducir hasta un 30% los gastos de operatividad, debido a la estructura con la que se encuentra realizada.\u00a0La separaci\u00f3n entre el revestimiento y el cerramiento permite instalar una capa aislante que favorece la libre circulaci\u00f3n del aire por la c\u00e1mara.<\/p>\n<p style=\"text-align: left;\">Las fachadas ventiladas cumplen con requerimientos espec\u00edficos para poder realizar su funcionalidad tanto en verano como en invierno, pues es diferente su funcionamiento en cada tipo de temperatura, de esta manera se busca mantener a los habitantes en un confort constante.<\/p>\n<p style=\"text-align: left;\">En verano los rayos solares suelen ser de mayor intensidad, siendo la fachada ventilada la que los recibe de manera directa. En este caso el aire albergado se calienta y reduce su densidad. Cuando esto ocurre el aire caliente asciende por convecci\u00f3n y deja espacio para el aire fresco.<\/p>\n<p style=\"text-align: left;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-964\" src=\"https:\/\/grupobasica.com\/website\/wp-content\/uploads\/2016\/08\/chedaui-02.jpg\" alt=\"chedaui-02\" width=\"950\" height=\"620\" srcset=\"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-02.jpg 950w, https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-02-300x196.jpg 300w, https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-02-768x501.jpg 768w, https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-02-400x260.jpg 400w, https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-02-700x457.jpg 700w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/p>\n<p style=\"text-align: left;\">Se le llama \u201cefecto chimenea\u201d a la funci\u00f3n que realiza la fachada ventilada en \u00e9poca de verano, pues evita la acumulaci\u00f3n de calor en la fachada del edificio. \u00a0Gracias a este funcionamiento se logra el ahorro de energ\u00eda en la edificaci\u00f3n y con ello la reducci\u00f3n de costos de operatividad.<\/p>\n<p style=\"text-align: left;\">Diferentes estudios afirman que al utilizar una fachada ventilada se reduce hasta un 30% los costos operativos de gas, energ\u00eda y electricidad.\u00a0Otra ventaja que las fachadas ventiladas ofrecen, es la reducci\u00f3n de gastos de mantenimiento, ya que es m\u00ednimo gracias a la correcta elecci\u00f3n de las placas de revestimiento. En <strong>Basica<sup>\u00ae<\/sup><\/strong> nuestro objetivo es realizar una fachada capaz de cumplir tus requerimientos y a\u00f1adir mayor eficiencia a la edificaci\u00f3n. Todo ello con la aplicaci\u00f3n y selecci\u00f3n de los materiales correctos en conjunto con el an\u00e1lisis que realiza nuestro equipo especializado en fachadas.<\/p>\n<p style=\"text-align: left;\">Cont\u00e1ctanos y agenda tu cita para un asesoramiento personalizado visitando <a href=\"https:\/\/grupobasica.com\/en\/website\/contacto\/\">www.grupobasica.com\/contacto<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Una de las mayores ventajas de una fachada ventilada es la eficiencia energ\u00e9tica que brinda a las edificaciones. Ya que su aislamiento es capaz de reducir hasta un 30% los gastos de operatividad, debido a la estructura con la que&#8230;<\/p>","protected":false},"author":2,"featured_media":963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28,19],"tags":[27,16,22,12],"class_list":["post-962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diseno","category-proyectos-basica","tag-asesoria","tag-consultoria","tag-fachadas","tag-fachadas-ventiladas"],"yoast_head":"\n<title>\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano? | Grupo Basica\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano? | Grupo Basica\u00ae\" \/>\n<meta property=\"og:description\" content=\"Una de las mayores ventajas de una fachada ventilada es la eficiencia energ\u00e9tica que brinda a las edificaciones. Ya que su aislamiento es capaz de reducir hasta un 30% los gastos de operatividad, debido a la estructura con la que...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Basica\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-30T22:26:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.website-122f066c.bangweb.site\/wp-content\/uploads\/2016\/08\/chedaui-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adriana liv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adriana liv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/\"},\"author\":{\"name\":\"adriana liv\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/person\\\/afa17a59e6bb68be638d482da25979c5\"},\"headline\":\"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano?\",\"datePublished\":\"2016-08-30T22:26:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/\"},\"wordCount\":345,\"publisher\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/chedaui-01.jpg\",\"keywords\":[\"asesor\u00eda\",\"consultor\u00eda\",\"fachadas\",\"fachadas ventiladas\"],\"articleSection\":[\"Dise\u00f1o\",\"Proyectos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/\",\"name\":\"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano? | Grupo Basica\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/chedaui-01.jpg\",\"datePublished\":\"2016-08-30T22:26:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/chedaui-01.jpg\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/chedaui-01.jpg\",\"width\":950,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/grupobasica.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#website\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/\",\"name\":\"Grupo Basica\u00a9\",\"description\":\"Consultor\u00eda, Dise\u00f1o y Sistema de Fachadas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\"},\"alternateName\":\"Basica\u00a9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#organization\",\"name\":\"Grupo Basica\u00a9\",\"alternateName\":\"Basica\u00a9\",\"url\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-grupobasica-696px.png\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-grupobasica-696px.png\",\"width\":696,\"height\":696,\"caption\":\"Grupo Basica\u00a9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.website-122f066c.bangweb.site\\\/#\\\/schema\\\/person\\\/afa17a59e6bb68be638d482da25979c5\",\"name\":\"adriana liv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"url\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"contentUrl\":\"https:\\\/\\\/grupobasica.com\\\/wp-content\\\/litespeed\\\/avatar\\\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235\",\"caption\":\"adriana liv\"},\"url\":\"https:\\\/\\\/grupobasica.com\\\/en\\\/author\\\/adriana\\\/\"}]}<\/script>\n","yoast_head_json":{"title":"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano? | Grupo Basica\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano? | Grupo Basica\u00ae","og_description":"Una de las mayores ventajas de una fachada ventilada es la eficiencia energ\u00e9tica que brinda a las edificaciones. Ya que su aislamiento es capaz de reducir hasta un 30% los gastos de operatividad, debido a la estructura con la que...","og_url":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/","og_site_name":"Grupo Basica\u00ae","article_published_time":"2016-08-30T22:26:56+00:00","og_image":[{"width":950,"height":620,"url":"https:\/\/www.website-122f066c.bangweb.site\/wp-content\/uploads\/2016\/08\/chedaui-01.jpg","type":"image\/jpeg"}],"author":"adriana liv","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adriana liv","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/#article","isPartOf":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/"},"author":{"name":"adriana liv","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/person\/afa17a59e6bb68be638d482da25979c5"},"headline":"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano?","datePublished":"2016-08-30T22:26:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/"},"wordCount":345,"publisher":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-01.jpg","keywords":["asesor\u00eda","consultor\u00eda","fachadas","fachadas ventiladas"],"articleSection":["Dise\u00f1o","Proyectos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/","url":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/","name":"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano? | Grupo Basica\u00ae","isPartOf":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/#primaryimage"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-01.jpg","datePublished":"2016-08-30T22:26:56+00:00","breadcrumb":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/#primaryimage","url":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-01.jpg","contentUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2016\/08\/chedaui-01.jpg","width":950,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/www.website-122f066c.bangweb.site\/nos-protege-la-fachada-ventilada-del-calor-en-tiempos-verano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/grupobasica.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo nos protege la fachada ventilada del calor en tiempos de verano?"}]},{"@type":"WebSite","@id":"https:\/\/www.website-122f066c.bangweb.site\/#website","url":"https:\/\/www.website-122f066c.bangweb.site\/","name":"Grupo Basica\u00a9","description":"Consultor\u00eda, Dise\u00f1o y Sistema de Fachadas","publisher":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization"},"alternateName":"Basica\u00a9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.website-122f066c.bangweb.site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.website-122f066c.bangweb.site\/#organization","name":"Grupo Basica\u00a9","alternateName":"Basica\u00a9","url":"https:\/\/www.website-122f066c.bangweb.site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/logo\/image\/","url":"https:\/\/grupobasica.com\/wp-content\/uploads\/2023\/03\/logo-grupobasica-696px.png","contentUrl":"https:\/\/grupobasica.com\/wp-content\/uploads\/2023\/03\/logo-grupobasica-696px.png","width":696,"height":696,"caption":"Grupo Basica\u00a9"},"image":{"@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.website-122f066c.bangweb.site\/#\/schema\/person\/afa17a59e6bb68be638d482da25979c5","name":"adriana liv","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","url":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","contentUrl":"https:\/\/grupobasica.com\/wp-content\/litespeed\/avatar\/864d48a4709158026a0c95d0dcc43c8f.jpg?ver=1783523235","caption":"adriana liv"},"url":"https:\/\/grupobasica.com\/en\/author\/adriana\/"}]}},"_links":{"self":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":0,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/media\/963"}],"wp:attachment":[{"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupobasica.com\/en\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}